{"id":9778,"date":"2026-02-06T10:43:34","date_gmt":"2026-02-06T09:43:34","guid":{"rendered":"https:\/\/www.zeelandia-vanbelzen.de\/?p=9778"},"modified":"2026-07-02T21:39:56","modified_gmt":"2026-07-02T19:39:56","slug":"filete-de-pez-espada","status":"publish","type":"post","link":"https:\/\/www.zeelandia-vanbelzen.de\/es\/schwertfischfilet\/","title":{"rendered":"Filete de pez espada"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":17351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,80],"tags":[],"class_list":["post-9778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fisch","category-filets","category-70","category-80","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schwertfischfilet | Zeelandia van Belzen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zeelandia-vanbelzen.de\/es\/filete-de-pez-espada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schwertfischfilet | Zeelandia van Belzen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zeelandia-vanbelzen.de\/es\/filete-de-pez-espada\/\" \/>\n<meta property=\"og:site_name\" content=\"Zeelandia van Belzen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZeelandiaVanBelzen\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-06T09:43:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T19:39:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zeelandia-vanbelzen.de\/wp-content\/uploads\/2026\/06\/1040_Schwertfischfilet.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"JoHero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"JoHero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/\"},\"author\":{\"name\":\"JoHero\",\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/#\\\/schema\\\/person\\\/262546b1365c4d0b6721b68d8951188e\"},\"headline\":\"Schwertfischfilet\",\"datePublished\":\"2026-02-06T09:43:34+00:00\",\"dateModified\":\"2026-07-02T19:39:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/\"},\"wordCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/1040_Schwertfischfilet.png\",\"articleSection\":[\"Fisch\",\"Filets\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/\",\"url\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/\",\"name\":\"Schwertfischfilet | Zeelandia van Belzen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/1040_Schwertfischfilet.png\",\"datePublished\":\"2026-02-06T09:43:34+00:00\",\"dateModified\":\"2026-07-02T19:39:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/1040_Schwertfischfilet.png\",\"contentUrl\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/1040_Schwertfischfilet.png\",\"width\":1920,\"height\":865,\"caption\":\"Schwertfischfilet Zeelandia van Belzen Fischgro\u00dfhandel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/fr\\\/schwertfischfilet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schwertfischfilet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/#website\",\"url\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/\",\"name\":\"Zeelandia van Belzen GmbH\",\"description\":\"Fischgro\u00dfhandel\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/#organization\"},\"alternateName\":\"Zeelandia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/#organization\",\"name\":\"Zeelandia van Belzen GmbH\",\"alternateName\":\"Zeelandia van Belzen\",\"url\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Zeelandia-van-Belzen_Logo_Admin.png\",\"contentUrl\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Zeelandia-van-Belzen_Logo_Admin.png\",\"width\":300,\"height\":129,\"caption\":\"Zeelandia van Belzen GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZeelandiaVanBelzen\",\"http:\\\/\\\/instagram.com\\\/ZeelandiaVanBelzen\",\"https:\\\/\\\/www.youtube.com\\\/@ZeelandiaVanBelzen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/#\\\/schema\\\/person\\\/262546b1365c4d0b6721b68d8951188e\",\"name\":\"JoHero\",\"url\":\"https:\\\/\\\/www.zeelandia-vanbelzen.de\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filete de pez espada | Zeelandia van Belzen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zeelandia-vanbelzen.de\/es\/filete-de-pez-espada\/","og_locale":"es_ES","og_type":"article","og_title":"Schwertfischfilet | Zeelandia van Belzen","og_url":"https:\/\/www.zeelandia-vanbelzen.de\/es\/filete-de-pez-espada\/","og_site_name":"Zeelandia van Belzen","article_publisher":"https:\/\/www.facebook.com\/ZeelandiaVanBelzen","article_published_time":"2026-02-06T09:43:34+00:00","article_modified_time":"2026-07-02T19:39:56+00:00","og_image":[{"width":1920,"height":865,"url":"https:\/\/www.zeelandia-vanbelzen.de\/wp-content\/uploads\/2026\/06\/1040_Schwertfischfilet.png","type":"image\/png"}],"author":"JoHero","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"JoHero","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/#article","isPartOf":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/"},"author":{"name":"JoHero","@id":"https:\/\/www.zeelandia-vanbelzen.de\/#\/schema\/person\/262546b1365c4d0b6721b68d8951188e"},"headline":"Schwertfischfilet","datePublished":"2026-02-06T09:43:34+00:00","dateModified":"2026-07-02T19:39:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/"},"wordCount":1,"publisher":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/#organization"},"image":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zeelandia-vanbelzen.de\/wp-content\/uploads\/2026\/06\/1040_Schwertfischfilet.png","articleSection":["Fisch","Filets"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/","url":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/","name":"Filete de pez espada | Zeelandia van Belzen","isPartOf":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/#primaryimage"},"image":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zeelandia-vanbelzen.de\/wp-content\/uploads\/2026\/06\/1040_Schwertfischfilet.png","datePublished":"2026-02-06T09:43:34+00:00","dateModified":"2026-07-02T19:39:56+00:00","breadcrumb":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/#primaryimage","url":"https:\/\/www.zeelandia-vanbelzen.de\/wp-content\/uploads\/2026\/06\/1040_Schwertfischfilet.png","contentUrl":"https:\/\/www.zeelandia-vanbelzen.de\/wp-content\/uploads\/2026\/06\/1040_Schwertfischfilet.png","width":1920,"height":865,"caption":"Schwertfischfilet Zeelandia van Belzen Fischgro\u00dfhandel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zeelandia-vanbelzen.de\/fr\/schwertfischfilet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.zeelandia-vanbelzen.de\/"},{"@type":"ListItem","position":2,"name":"Schwertfischfilet"}]},{"@type":"WebSite","@id":"https:\/\/www.zeelandia-vanbelzen.de\/#website","url":"https:\/\/www.zeelandia-vanbelzen.de\/","name":"Zeelandia van Belzen GmbH","description":"Venta de pescado al por mayor","publisher":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/#organization"},"alternateName":"Zeelandia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zeelandia-vanbelzen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.zeelandia-vanbelzen.de\/#organization","name":"Zeelandia van Belzen GmbH","alternateName":"Zeelandia van Belzen","url":"https:\/\/www.zeelandia-vanbelzen.de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zeelandia-vanbelzen.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.zeelandia-vanbelzen.de\/wp-content\/uploads\/2025\/08\/Zeelandia-van-Belzen_Logo_Admin.png","contentUrl":"https:\/\/www.zeelandia-vanbelzen.de\/wp-content\/uploads\/2025\/08\/Zeelandia-van-Belzen_Logo_Admin.png","width":300,"height":129,"caption":"Zeelandia van Belzen GmbH"},"image":{"@id":"https:\/\/www.zeelandia-vanbelzen.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ZeelandiaVanBelzen","http:\/\/instagram.com\/ZeelandiaVanBelzen","https:\/\/www.youtube.com\/@ZeelandiaVanBelzen"]},{"@type":"Person","@id":"https:\/\/www.zeelandia-vanbelzen.de\/#\/schema\/person\/262546b1365c4d0b6721b68d8951188e","name":"JoHero","url":"https:\/\/www.zeelandia-vanbelzen.de\/es\/author\/admin\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:49:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/posts\/9778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/comments?post=9778"}],"version-history":[{"count":1,"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/posts\/9778\/revisions"}],"predecessor-version":[{"id":21906,"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/posts\/9778\/revisions\/21906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/media\/17351"}],"wp:attachment":[{"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/media?parent=9778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/categories?post=9778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zeelandia-vanbelzen.de\/es\/wp-json\/wp\/v2\/tags?post=9778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}